{"id":8,"count":8,"description":"","link":"https:\/\/seateroo.com\/nl\/category\/overige\/","name":"Overige","slug":"overige","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Overige - Seateroo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seateroo.com\/nl\/category\/overige\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Overige - Seateroo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seateroo.com\/nl\/category\/overige\/\" \/>\n<meta property=\"og:site_name\" content=\"Seateroo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/seateroo.com\/nl\/category\/overige\/\",\"url\":\"https:\/\/seateroo.com\/nl\/category\/overige\/\",\"name\":\"Overige - Seateroo\",\"isPartOf\":{\"@id\":\"https:\/\/seateroo.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/seateroo.com\/nl\/category\/overige\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/seateroo.com\/nl\/category\/overige\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/seateroo.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Overige\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/seateroo.com\/#website\",\"url\":\"https:\/\/seateroo.com\/\",\"name\":\"Seateroo\",\"description\":\"Travel discount blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/seateroo.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Overige - Seateroo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seateroo.com\/nl\/category\/overige\/","og_locale":"nl_NL","og_type":"article","og_title":"Overige - Seateroo","og_url":"https:\/\/seateroo.com\/nl\/category\/overige\/","og_site_name":"Seateroo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/seateroo.com\/nl\/category\/overige\/","url":"https:\/\/seateroo.com\/nl\/category\/overige\/","name":"Overige - Seateroo","isPartOf":{"@id":"https:\/\/seateroo.com\/#website"},"breadcrumb":{"@id":"https:\/\/seateroo.com\/nl\/category\/overige\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/seateroo.com\/nl\/category\/overige\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seateroo.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Overige"}]},{"@type":"WebSite","@id":"https:\/\/seateroo.com\/#website","url":"https:\/\/seateroo.com\/","name":"Seateroo","description":"Travel discount blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seateroo.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/seateroo.com\/nl\/wp-json\/wp\/v2\/categories\/8"}],"collection":[{"href":"https:\/\/seateroo.com\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/seateroo.com\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/seateroo.com\/nl\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}